{"id":8874,"date":"2017-11-16T14:06:16","date_gmt":"2017-11-16T19:06:16","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/"},"modified":"2025-11-06T11:54:09","modified_gmt":"2025-11-06T16:54:09","slug":"como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/","title":{"rendered":"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas. Fue entonces cuando la junta dio un paso al frente.\n<\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<div style=\"width:200px;margin:20px auto;margin-bottom:0px\"><em>\u00bfMerece la pena QuakerSpeak 1 $ por v\u00eddeo?<\/em><br \/>\n<a href=\"https:\/\/fdsj.nl\/patreon2\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/2017\/05\/patreon_logo-small.png\"><\/a><\/div>\n<div id=\"Transcripci\u00f3n-link-8874\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8874, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8874\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8874\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>As\u00ed que viv\u00eda en Sacramento cuando empec\u00e9 a pensar en la transici\u00f3n a hombre y sab\u00eda que no iba a empezar ese proceso hasta que volviera a Virginia de todos modos porque quer\u00eda tener una comunidad m\u00e1s establecida y a mi familia cerca para eso, as\u00ed que no fue hasta alrededor de 2001 que pude empezar realmente el proceso de transici\u00f3n.<\/p>\n<p class=\"chapter\">C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero<\/p>\n<p>Me llamo Ted Heck. Voy a la Junta de Los Amigos de Richmond (VA) y soy coordinador de servicios de salud para personas transg\u00e9nero del estado. <\/p>\n<p>Era solo una cuesti\u00f3n de ser mi verdadero yo y sab\u00eda que Los Amigos lo valorar\u00edan, incluso si a algunos les costara un poco o se sintieran un poco inc\u00f3modos, sab\u00eda que se valorar\u00eda. Creo que saber eso me dio una especie de base y apoyo para poder seguir adelante. <\/p>\n<p class=\"chapter\">Pidiendo apoyo a la Junta<\/p>\n<p>Cuando descubr\u00ed mi cronograma para comenzar la transici\u00f3n, me di cuenta de que iba a necesitar encontrar una manera de cont\u00e1rselo a la gente sin tener que explic\u00e1rselo a cada persona, as\u00ed que ped\u00ed un comit\u00e9 de claridad. Fui bastante espec\u00edfico cuando ped\u00ed esto, que quer\u00eda que el comit\u00e9 me ayudara a averiguar c\u00f3mo cont\u00e1rselo a la junta. Aunque lo expliqu\u00e9 con bastante detalle, todav\u00eda hubo cierta confusi\u00f3n entre las personas a las que ped\u00ed que formaran parte del comit\u00e9. Pensaron que quer\u00eda ayuda para decidir si hacer la transici\u00f3n o no. As\u00ed que nuestra primera conversaci\u00f3n fue: \u201cNo, eso est\u00e1 resuelto. No hay duda de si eso va a suceder. Definitivamente va a suceder. Con lo que realmente necesito ayuda es con averiguar c\u00f3mo cont\u00e1rselo a todo el mundo\u201d.    <\/p>\n<p class=\"chapter\">C\u00f3mo se lo contamos a la Junta<\/p>\n<p>Despu\u00e9s de reflexionar sobre eso durante un tiempo, se nos ocurri\u00f3 una gran estrategia que consist\u00eda en que yo escribiera una carta que se publicar\u00eda en el bolet\u00edn y que formar\u00eda parte de un art\u00edculo m\u00e1s extenso del comit\u00e9 de claridad invitando a la gente a ponerse en contacto con ellos si ten\u00edan preguntas para que no me llegaran todas las preguntas a m\u00ed. As\u00ed que eso fue muy bien. Me sent\u00ed muy apoyado y la gente se puso en contacto conmigo, pero no de una manera abrumadora y la gente fue muy solidaria y simplemente genial al respecto. Hubo un individuo que m\u00e1s tarde descubr\u00ed que se sent\u00eda inc\u00f3modo con ello y llev\u00f3 su preocupaci\u00f3n a Ministerio y Adoraci\u00f3n y Ministerio y Adoraci\u00f3n le dijo que era su problema. As\u00ed que eso fue genial. Pero bueno, creo que la mayor\u00eda de las personas trans no tienen la experiencia que yo tuve y estoy muy agradecido de haber recibido tanto apoyo.     <\/p>\n<p class=\"chapter\">Una Minuta de apoyo<\/p>\n<p>La Junta de Richmond finalmente se anim\u00f3 a hacer una minuta que da la bienvenida deliberadamente a las personas transg\u00e9nero. Es interesante porque no habr\u00eda pensado que importar\u00eda tanto, pero una vez que estaba sucediendo y est\u00e1bamos hablando de ello en la junta, me di cuenta de que en realidad s\u00ed importaba. Una cosa es saber que la gente te apoya, pero tenerlo expl\u00edcitamente declarado de manera oficial y luego saber que la gente quiere tomar medidas adicionales para publicitar que la junta apoya m\u00e1s all\u00e1 de la comunidad de la junta, realmente hace la diferencia. Cuando hay tantos lugares en el mundo donde o bien te sientes no bienvenido o bien te sientes inseguro sobre si eres bienvenido, es realmente importante tener un espacio como ese, y tener eso como parte de mi junta mensual es realmente importante.   <\/p>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" title=\"Suscr\u00edbete\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a>Consulta una lista<\/a> de todos los v\u00eddeos que hemos producido.<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<\/ul>\n<h3>Preguntas para el debate:<\/h3>\n<ul>\n<li>\u00bfC\u00f3mo pueden las juntas apoyar mejor a un Amigo que necesita hacer un anuncio delicado? \u00bfAlguna vez has tenido que contarle a toda tu comunidad de la junta algo que te daba miedo o te hac\u00eda sentir vulnerable? <\/li>\n<li>Ted dice que la publicaci\u00f3n por parte de su junta de una minuta favorable a las personas transg\u00e9nero fue importante porque, \u201ccuando hay tantos lugares en el mundo donde o bien te sientes no bienvenido o bien te sientes inseguro sobre si eres bienvenido, es realmente importante tener un espacio como ese, y tener eso como parte de mi junta mensual es realmente importante\u201d. \u00bfC\u00f3mo se asegura tu junta de que la gente sepa que es bienvenida?\n<\/li>\n<\/ul>\n<p><\/div>\n","protected":false},"featured_media":5969,"comment_status":"open","ping_status":"closed","template":"","categories":[263,264],"tags":[325,338],"class_list":["post-8874","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-entrevista","category-lgbtq","tag-cuaqueros-lgbtq","tag-temporada-4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2017\/11\/how-told-meeting-transgender-TITLE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/\",\"name\":\"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/how-told-meeting-transgender-TITLE.png\",\"datePublished\":\"2017-11-16T19:06:16+00:00\",\"dateModified\":\"2025-11-06T16:54:09+00:00\",\"description\":\"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/how-told-meeting-transgender-TITLE.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/how-told-meeting-transgender-TITLE.png\",\"width\":1280,\"height\":720,\"caption\":\"Haz clic para ver: \u201cC\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak","description":"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak","og_description":"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.","og_url":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:54:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2017\/11\/how-told-meeting-transgender-TITLE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/","url":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/","name":"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2017\/11\/how-told-meeting-transgender-TITLE.png","datePublished":"2017-11-16T19:06:16+00:00","dateModified":"2025-11-06T16:54:09+00:00","description":"Cuando Ted decidi\u00f3 hacer la transici\u00f3n a hombre, sab\u00eda que quer\u00eda cont\u00e1rselo a su junta, pero no quer\u00eda un aluvi\u00f3n de preguntas.","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2017\/11\/how-told-meeting-transgender-TITLE.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2017\/11\/how-told-meeting-transgender-TITLE.png","width":1280,"height":720,"caption":"Haz clic para ver: \u201cC\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/como-le-conte-a-mi-junta-cuaquera-que-soy-transgenero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo le cont\u00e9 a mi Junta cu\u00e1quera que soy transg\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/5969"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}