{"id":8872,"date":"2016-04-07T15:02:34","date_gmt":"2016-04-07T19:02:34","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/"},"modified":"2025-11-06T11:53:55","modified_gmt":"2025-11-06T16:53:55","slug":"puede-haber-una-respuesta-no-violenta-al-terrorismo","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/","title":{"rendered":"\u00bfPuede haber una respuesta no violenta al terrorismo?"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">Las 8 estrategias no violentas del profesor cu\u00e1quero George Lakey para responder al terrorismo despertaron el inter\u00e9s del Pent\u00e1gono. Descubre qu\u00e9 pas\u00f3 despu\u00e9s. <\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<div id=\"Transcripci\u00f3n-link-8872\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8872, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8872\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8872\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a title=\"Suscr\u00edbete\" href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<\/ul>\n<h3>Preguntas para el debate:<\/h3>\n<ul>\n<li>\u00bfQu\u00e9 opinas de la idea de que la sanaci\u00f3n puede ser una estrategia de defensa exitosa contra el terrorismo?<\/li>\n<li>George Lakey califica al Pent\u00e1gono como una herramienta \u201cinapropiada\u201d para lidiar con el terrorismo. \u00bfEst\u00e1s de acuerdo? \u00bfQu\u00e9 ser\u00eda m\u00e1s apropiado, considerando los desaf\u00edos de defensa que enfrentamos hoy?  <\/li>\n<li>George Lakey describe el sistema pol\u00edtico estadounidense como manipulado en contra de alternativas no violentas que podr\u00edan defender mejor a los inocentes contra el terrorismo. \u00bfQu\u00e9 se puede hacer para cambiar el sistema? <\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Como experimento, como estaba dando clases aqu\u00ed en Swarthmore College, decid\u00ed ofrecer un curso llamado \u201cRespuestas No Violentas al Terrorismo\u201d y ver si alguien vendr\u00eda. Tuvimos que sortear el curso, hab\u00eda tantos estudiantes entusiasmados con este enfoque diferente. <\/p>\n<p class=\"chapter\">\u00bfPuede haber una respuesta no violenta al terrorismo?<\/p>\n<p>Su trabajo consist\u00eda en escribir. Cada estudiante ten\u00eda que elegir un pa\u00eds que actualmente est\u00e9 amenazado por el terrorismo; conocer ese pa\u00eds: sus fortalezas, sus debilidades; y desarrollar una estrategia de defensa contra la amenaza, una estrategia que ser\u00eda de car\u00e1cter no violento. Ese fue su trabajo de fin de curso para el semestre.  <\/p>\n<p class=\"chapter\">Las 8 herramientas de la defensa no violenta<\/p>\n<p>Hubo ocho herramientas diferentes que descubr\u00ed en mi investigaci\u00f3n que han sido utilizadas, en realidad, por varios estados-naci\u00f3n como modos de defensa. Por ejemplo, una de esas herramientas, quer\u00edas un ejemplo, una de esas herramientas es el desarrollo econ\u00f3mico. Haz desarrollo econ\u00f3mico en el \u00e1rea donde est\u00e1 el principal campo de reclutamiento para terroristas, porque los terroristas muy a menudo est\u00e1n motivados por la injusticia econ\u00f3mica y la opresi\u00f3n econ\u00f3mica. Si cambias esa situaci\u00f3n y proporcionas empleos abundantes, muchas de las personas que de otro modo decidir\u00edan seguir una carrera de terrorismo conseguir\u00e1n un trabajo y, ya sabes, ser\u00e1n ciudadanos honestos. Y entonces, esa es una de las ocho.    <\/p>\n<p class=\"chapter\">La sanaci\u00f3n como herramienta estrat\u00e9gica<\/p>\n<p>Lo que hace el terror, incluso la amenaza de terror hasta cierto punto, pero lo que hace el acto real de terror es traumatizar a las personas m\u00e1s afectadas y a las personas que las conocen. El trauma, entonces, toma forma pol\u00edtica y aumenta la probabilidad de que esa naci\u00f3n haga cosas al atacante que aumenten la cantidad del ataque. Eso es lo que pas\u00f3 el 11-S. Estados Unidos, por su respuesta a Afganist\u00e1n y luego a Irak, aument\u00f3 el n\u00famero total de terroristas disponibles en el mundo, aument\u00f3 la prominencia de Osama Bin Laden. Fue simplemente asombroso\u2026 Estados Unidos decidi\u00f3 ser el principal reclutador de terroristas contra s\u00ed mismo. Pero lo hizo no porque sea tan est\u00fapido como para querer reclutar terroristas para Osama Bin Laden, no intencionalmente. Pero porque el trauma en s\u00ed oblig\u00f3 a Estados Unidos a hacer esta locura que nadie pragm\u00e1tico querr\u00eda hacer. Entonces, otra herramienta de estas ocho es entrar directamente en un modo de sanaci\u00f3n para las personas que fueron traumatizadas. En este caso, en Estados Unidos, fue realmente toda la poblaci\u00f3n la que fue traumatizada por la experiencia del 11-S. Entonces, ese es otro ejemplo de una herramienta.         <\/p>\n<p class=\"chapter\">Implementando la no violencia como pol\u00edtica<\/p>\n<p>Es dif\u00edcil resumir esas herramientas, porque tom\u00f3 todo un semestre exponerlas realmente, para que los estudiantes tuvieran suficiente capacidad para operar con ellas. Lo hicieron. Hicieron trabajos fant\u00e1sticos. Mientras tanto, el Pent\u00e1gono se enter\u00f3 de esto y me pidi\u00f3 que bajara. Y entonces, baj\u00e9 y me reun\u00ed con una unidad de pol\u00edtica del Pent\u00e1gono que ten\u00eda que ver con la respuesta al terrorismo. Estos eran profesionales en el campo. Yo no soy un profesional en el campo del terrorismo, pero all\u00ed estaban.      <\/p>\n<p>Entonces, lo expuse todo y dije, al principio, la \u00fanica raz\u00f3n por la que quiero exponer estas ocho para ustedes, no es solo porque los estudiantes, que definitivamente no son expertos, son estudiantes universitarios, pudieron dar tanto sentido a la planificaci\u00f3n de la defensa para los diversos pa\u00edses que eligieron, incluyendo Israel, incluyendo Estados Unidos, incluyendo Indonesia y otros pa\u00edses que estaban amenazados. No solo los estudiantes pudieron escribir trabajos que ten\u00edan tanto sentido, sino tambi\u00e9n, ustedes, como expertos, espero que muestren m\u00e1s sobre c\u00f3mo las sinergias ocurrir\u00e1n por la combinaci\u00f3n de las ocho. Porque, s\u00ed, hay pa\u00edses que han probado el n\u00famero dos y el n\u00famero cinco, pero \u00bfqu\u00e9 pasa si tomas las ocho y te olvidas de la respuesta militar, simplemente dices, en lugar de una respuesta militar, tendremos una respuesta no violenta? Usen esas ocho sin\u00e9rgicamente entre s\u00ed, para que el todo sea mayor que la suma de sus partes. Quiero que ustedes, como expertos, me den ese tipo de retroalimentaci\u00f3n.    <\/p>\n<p>En cambio, lo que obtuve desde su punto de vista fue que el gobierno de Estados Unidos no opera de esa manera, el gobierno de Estados Unidos no opera en t\u00e9rminos de enfoques alternativos sist\u00e9micos. No hay forma de que nuestra pol\u00edtica pueda manejar eso. Est\u00e1 demasiado polarizado. La forma en que las ideas llegan al presidente, y ciertamente una alternativa de este alcance tendr\u00eda que llegar al presidente, la forma en que las propuestas llegan al presidente las recorta, las somete al m\u00ednimo com\u00fan denominador entre las diversas agencias que est\u00e1n involucradas, y no hay forma de que ese tipo de paquete, tan prometedor como es&#8230; De hecho, lo que dijeron los expertos, \u201cNo tenemos ning\u00fan problema con nada de lo que ha dicho, pero ese tipo de cambio sist\u00e9mico est\u00e1 m\u00e1s all\u00e1 de la capacidad del gobierno de Estados Unidos\u201d.<\/p>\n<p>Entonces, estaba agradecido por el curso, que he impartido un par de veces desde entonces, no solo como una indicaci\u00f3n de c\u00f3mo los estudiantes universitarios pueden hacer un trabajo brillante si se les da una herramienta que es apropiada, en lugar de la herramienta que es inapropiada, llamada el Pent\u00e1gono. Y, tambi\u00e9n, que aprend\u00ed una segunda lecci\u00f3n, que el gobierno de Estados Unidos est\u00e1 configurado de tal manera que no puede hacer una respuesta no violenta creativa que ser\u00eda mucho m\u00e1s efectiva que la respuesta que hemos estado haciendo. <\/p>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":5237,"comment_status":"open","ping_status":"closed","template":"","categories":[267,263,271,266],"tags":[320,331,319,311,335],"class_list":["post-8872","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-activismo-cuaquero","category-entrevista","category-ministerio-cuaquero","category-popular","tag-activismo-cuaquero","tag-george-lakey","tag-la-no-violencia-de-los-amigos","tag-ministerio-cuaquero","tag-temporada-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2016\/04\/nonviolent-response-to-terrorism-PLAY.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/\",\"name\":\"\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/04\\\/nonviolent-response-to-terrorism-PLAY.png\",\"datePublished\":\"2016-04-07T19:02:34+00:00\",\"dateModified\":\"2025-11-06T16:53:55+00:00\",\"description\":\"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/04\\\/nonviolent-response-to-terrorism-PLAY.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/04\\\/nonviolent-response-to-terrorism-PLAY.png\",\"width\":1280,\"height\":720,\"caption\":\"Haz clic para ver: \u201c\u00bfUna respuesta no violenta al terrorismo?\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/puede-haber-una-respuesta-no-violenta-al-terrorismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfPuede haber una respuesta no violenta al terrorismo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak","description":"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak","og_description":"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.","og_url":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:53:55+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2016\/04\/nonviolent-response-to-terrorism-PLAY.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/","url":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/","name":"\u00bfPuede haber una respuesta no violenta al terrorismo? - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2016\/04\/nonviolent-response-to-terrorism-PLAY.png","datePublished":"2016-04-07T19:02:34+00:00","dateModified":"2025-11-06T16:53:55+00:00","description":"Reflexiones del acad\u00e9mico cu\u00e1quero y activista por la paz George Lakey.","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2016\/04\/nonviolent-response-to-terrorism-PLAY.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2016\/04\/nonviolent-response-to-terrorism-PLAY.png","width":1280,"height":720,"caption":"Haz clic para ver: \u201c\u00bfUna respuesta no violenta al terrorismo?\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/puede-haber-una-respuesta-no-violenta-al-terrorismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"\u00bfPuede haber una respuesta no violenta al terrorismo?"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/5237"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}