{"id":8838,"date":"2014-08-14T11:37:40","date_gmt":"2014-08-14T15:37:40","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/consejos-para-hombres-blancos\/"},"modified":"2025-11-06T11:51:40","modified_gmt":"2025-11-06T16:51:40","slug":"consejos-para-hombres-blancos","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/","title":{"rendered":"Consejos para hombres blancos"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.<\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<div id=\"Transcripci\u00f3n-link-8838\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8838, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8838\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8838\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" title=\"Suscr\u00edbete\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li>M\u00fasica en este episodio: \u00abLive up to the Light That Thou Hast&#8221;. <a href=\"https:\/\/youtu.be\/vzgX50c9OEk\" target=\"_blank\" rel=\"noopener noreferrer\">Escucha la canci\u00f3n completa<\/a>.<\/li>\n<li>Descubre m\u00e1s sobre el taller de Diversidad de Niyonu Spann en <a href=\"https:\/\/www.fgcquaker.org\/sites\/www.fgcquaker.org\/files\/attachments\/Beyond%20Diversity%20101%20-%20Niyonu%20Spann.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">este ensayo<\/a> en el sitio web de la FGC<\/li>\n<li>\u00abDe hecho, podemos abolir la discriminaci\u00f3n sistem\u00e1tica dentro y fuera&#8221;. <a href=\"https:\/\/www.beyonddiversity101.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Descubre m\u00e1s<\/a> sobre \u201cBeyond Diversity 101\u201d<\/li>\n<li><a href=\"https:\/\/www.fgcquaker.org\/services\/help-your-meeting-challenge-racism\" target=\"_blank\" rel=\"noopener noreferrer\">Recursos para ayudar a tu Junta a desafiar el racismo<\/a><\/li>\n<li>Lee este art\u00edculo de Friends Journal: <a href=\"https:\/\/www.friendsjournal.org\/2003116\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u201cAvanzando hacia la integridad: Abordando la raza entre Los Amigos\u201d<\/a><\/li>\n<li><a href=\"https:\/\/www.fgcquaker.org\/explore\/quaker-way\" target=\"_blank\" rel=\"noopener noreferrer\">Explora el camino cu\u00e1quero<\/a> para ver si podr\u00eda ser adecuado para ti.<\/li>\n<li>\u00a1Adora con Los Amigos! Encuentra cu\u00e1queros cerca de ti en <a href=\"https:\/\/www.fgcquaker.org\/connect\/quaker-finder\" target=\"_blank\" rel=\"noopener noreferrer\">QuakerFinder<\/a> y en los <a href=\"https:\/\/www.friendsjournal.org\/meeting-listings\/\" target=\"_blank\" rel=\"noopener noreferrer\">listados de juntas<\/a> de Friends Journal <\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<li><a href=\"https:\/\/www.quakervoluntaryservice.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Quaker Voluntary Service<\/a> ofrece oportunidades para mujeres y hombres j\u00f3venes interesados en la transformaci\u00f3n social y personal a trav\u00e9s del trabajo de servicio y la vida en comunidad cu\u00e1quera.<\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Mi idea del cielo es que la gente pueda estar \u00abllena&#8221;, ser plenamente quien es y aportar sus dones o ser selectiva al respecto. Esa es realmente mi idea del cielo. <\/p>\n<p class=\"chapter\">Consejos para hombres blancos<\/p>\n<p><em>Vive de acuerdo con la verdad y recuerda, hijo m\u00edo<br \/>\nNunca est\u00e1s solo<br \/>\nNo, nunca<\/em><\/p>\n<p>Lo que he anhelado siempre es tener co-lo-que-sea. Co-l\u00edderes, co-facilitadores, co-m\u00fasicos que puedan darlo todo, donde yo pueda darlo todo y eso no signifique que luego se echen atr\u00e1s, porque \u00aberes demasiado fuerte con lo tuyo&#8221; o lo que sea. As\u00ed que esa es mi idea del cielo, as\u00ed que empezar\u00e9 por ah\u00ed.  <\/p>\n<p>Pero creo que es un momento en nuestra sociedad \u2014al menos aqu\u00ed en los EE. UU., que es donde he pasado la mayor parte de mi vida\u2014 en el que los hombres blancos en particular tienen un camino muy dif\u00edcil hacia la curaci\u00f3n, porque creo que muchos de los c\u00edrculos que definir\u00edamos como espacios de curaci\u00f3n o lugares espirituales o c\u00edrculos activistas se lanzan sobre los hombres blancos r\u00e1pidamente tan pronto como act\u00faan de alguna manera plenamente.<\/p>\n<p>As\u00ed que hay mucho&#8230; la gente est\u00e1 muy dispuesta a pillar a un hombre blanco haciendo algo mal (lo \u00abmalo&#8221;), hablando demasiado, hablando con demasiada audacia, estando demasiado contento de qui\u00e9n es, ya sabes, cualquier cosa de esas.<br \/>\n Y experiment\u00e9 esto mucho en Pendle Hill. Sent\u00ed que era una cultura que \u2014debido a que era principalmente blanca, de clase media, mujeres de mediana edad\u2014 era muy consciente de que la cultura no era muy propicia para que los hombres blancos actuaran de ninguna manera excepto de una manera muy humilde, atenuada. Una especie de forma de ser atenuada.  <\/p>\n<p>Y as\u00ed, cuando ocasionalmente ten\u00edamos un hombre blanco que no actuaba de esa manera, lo ve\u00eda pasarlo mal. Pero yo era muy consciente de eso y, por lo tanto, ya sabes, el mundo en general ha sido tan colonizado y aterrorizado por los hombres blancos que es muy dif\u00edcil equilibrarlo, pero donde pongo mi energ\u00eda en este momento es tratando de crear el espacio para \u00abTr\u00e1elo. Tr\u00e1elo. Tr\u00e1ete a ti mismo m\u00e1s plenamente&#8221;. Porque no creo que pueda sanar hasta que t\u00fa&#8230; ya sabes. No puedo ver como, \u00abVale, ponte en pausa mientras yo&#8230;&#8221;. Ya sabes, no creo que eso nos lleve a todos a estar completos.   <\/p>\n<p>As\u00ed que esa es mi opini\u00f3n. Entiendo completamente a los que dicen: \u00abDejad que los hombres blancos se sienten en la esquina y se callen mientras nosotros hacemos lo nuestro&#8221;. Entiendo de d\u00f3nde viene eso. Pero eso no es lo que quiero hacer. Probablemente debido a mi idea del cielo.    <\/p>\n<p><em>Oh, vive de acuerdo con la Luz que tienes<br \/>\nY m\u00e1s te ser\u00e1 concedido<br \/>\nTe ser\u00e1 concedido<br \/>\nOh, vive de acuerdo con la Luz que tienes<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":4493,"comment_status":"open","ping_status":"closed","template":"","categories":[275,263,271],"tags":[333,311,314],"class_list":["post-8838","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-cuaqueros-de-color-hablan","category-entrevista","category-ministerio-cuaquero","tag-amigos-de-color","tag-ministerio-cuaquero","tag-temporada-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consejos para hombres blancos - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consejos para hombres blancos - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2014\/08\/Niyonu-Advice-PLAY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/\",\"name\":\"Consejos para hombres blancos - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/08\\\/Niyonu-Advice-PLAY.jpg\",\"datePublished\":\"2014-08-14T15:37:40+00:00\",\"dateModified\":\"2025-11-06T16:51:40+00:00\",\"description\":\"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/08\\\/Niyonu-Advice-PLAY.jpg\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/08\\\/Niyonu-Advice-PLAY.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Haz clic para ver: consejos para hombres blancos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/consejos-para-hombres-blancos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Consejos para hombres blancos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consejos para hombres blancos - QuakerSpeak","description":"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/","og_locale":"es_ES","og_type":"article","og_title":"Consejos para hombres blancos - QuakerSpeak","og_description":"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.","og_url":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:51:40+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2014\/08\/Niyonu-Advice-PLAY.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/","url":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/","name":"Consejos para hombres blancos - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2014\/08\/Niyonu-Advice-PLAY.jpg","datePublished":"2014-08-14T15:37:40+00:00","dateModified":"2025-11-06T16:51:40+00:00","description":"Niyonu Spann, fundadora de Beyond Diversity 101, habla sobre su idea del cielo y c\u00f3mo invita a todo el mundo (incluidos los hombres blancos) a traerlo plenamente.","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2014\/08\/Niyonu-Advice-PLAY.jpg","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2014\/08\/Niyonu-Advice-PLAY.jpg","width":1280,"height":720,"caption":"Haz clic para ver: consejos para hombres blancos"},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/consejos-para-hombres-blancos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"Consejos para hombres blancos"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/4493"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}