{"id":8603,"date":"2015-10-29T14:22:44","date_gmt":"2015-10-29T18:22:44","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/los-amigos-y-la-justicia-para-los-migrantes\/"},"modified":"2025-11-06T11:43:42","modified_gmt":"2025-11-06T16:43:42","slug":"los-amigos-y-la-justicia-para-los-migrantes","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/","title":{"rendered":"Los Amigos y la justicia para los migrantes"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.\n<\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<p><a href=\"https:\/\/fdsj.nl\/afsc-immigration\" target=\"_blank\" rel=\"noopener noreferrer\">5 cosas que tu congregaci\u00f3n puede hacer para apoyar la justicia para los inmigrantes<\/a><\/p>\n<div id=\"Transcripci\u00f3n-link-8603\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8603, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8603\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8603\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" title=\"Suscr\u00edbete\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<li><a href=\"https:\/\/www.fcnl.org\" target=\"_blank\" rel=\"noopener noreferrer\">Visita FCNL<\/a> para presionar con Los Amigos en el Capitolio<\/li>\n<li><a href=\"https:\/\/www.afsc.org\/friends\" target=\"_blank\" rel=\"noopener noreferrer\">Trabaja por la paz con justicia<\/a> con AFSC.<\/li>\n<li><a href=\"https:\/\/www.fwccamericas.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aprende sobre la rica diversidad de los cu\u00e1queros en todo el mundo<\/a> con FWCC.<\/li>\n<\/ul>\n<h3>Preguntas para el debate:<\/h3>\n<ul>\n<li>Muchos de nosotros tenemos inmigrantes en nuestra historia familiar. \u00bfQu\u00e9 historias conocemos sobre el movimiento de nuestros antepasados, voluntario o forzado? \u00bfC\u00f3mo fue vivir en una nueva tierra?  <\/li>\n<li>Seg\u00fan la trabajadora por los derechos de los inmigrantes Lori Khamala, \u201cComo Amigos, tenemos mucho m\u00e1s que ofrecer a esta conversaci\u00f3n, sobre c\u00f3mo reconocemos la luz de Dios en cada individuo, c\u00f3mo tratamos a las personas en general, c\u00f3mo aceptamos un mandato b\u00edblico de acoger al extranjero\u201d. \u00bfEst\u00e1s de acuerdo? \u00bfQu\u00e9 tenemos que ofrecer?\n<\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Lori Fernald Khamala<br \/>\nNo estoy de acuerdo cuando escucho a la gente hablar de un \u201cproblema\u201d de inmigraci\u00f3n. No hay ning\u00fan problema con la inmigraci\u00f3n. La inmigraci\u00f3n no es el problema. La gente se mueve. La gente siempre se ha movido.<x id=\"gid_1\"><\/x>El problema son las pol\u00edticas que criminalizan a nuestros hermanos y hermanas inmigrantes. El problema son las pol\u00edticas que est\u00e1n destrozando familias y que no honran la dignidad humana de nuestros hermanos y hermanas que nacieron en otra tierra.     <\/p>\n<p>&lt;p class=&#8221;chapter&#8221;Los Amigos y la justicia para los migrantes<\/p>\n<p>Me llamo Fatima Cisse. Tengo 24 a\u00f1os, y cuando ten\u00eda 11, mi madre fue deportada de vuelta a Costa de Marfil. Recuerdo que llegu\u00e9 a casa del colegio y mi padre me dijo que la hab\u00edan arrestado, y me qued\u00e9 impactada porque mi madre nunca se hab\u00eda metido en problemas. Fue impactante.   <\/p>\n<p>El impacto en las familias<\/p>\n<p>En nuestra cultura, la madre es la que cuida de los ni\u00f1os y del hogar y de todo, as\u00ed que perdimos todo eso, y a mi padre, apenas lo ve\u00edamos: trabajando en dos empleos e intentando pagar las facturas y todo. As\u00ed que fue muy duro para nosotros. Hay mucho dolor detr\u00e1s de eso. Nos sentimos solos y no del todo juntos, como si hubiera piezas rotas en un rompecabezas.   <\/p>\n<p>Lori Fernald Khamala<br \/>\nVemos a millones de ni\u00f1os que viven en familias de estatus mixto. Esto significa que pueden ser ciudadanos estadounidenses, pero al menos uno de los padres es indocumentado. Tenemos millones de ni\u00f1os que viven en esta situaci\u00f3n de estatus mixto que produce una enorme cantidad de incertidumbre y miedo a la p\u00e9rdida de un progenitor por deportaci\u00f3n.  <\/p>\n<p>&lt;p class=&#8221;chapter&#8221;C\u00f3mo la ignorancia engendra el miedo<\/p>\n<p>Pedro Rios<br \/>\nCuando los pol\u00edticos hacen comentarios despectivos sobre los mexicanos o sobre personas de otros pa\u00edses, suele ser porque proviene de un lugar de miedo o de un lugar de ignorancia, o de un lugar de no haber tenido realmente la oportunidad de conocer e interactuar con los migrantes que han llegado recientemente a este pa\u00eds.<\/p>\n<p>Sanando nuestras comunidades<\/p>\n<p>Fatima Cisse<br \/>\nFinalmente, a los 16 a\u00f1os, un amigo de mi padre nos present\u00f3 al Servicio de los Amigos Americanos, y nos dieron una mejor imagen sobre la inmigraci\u00f3n y nos explicaron que cuando cumpliera 21 a\u00f1os, podr\u00eda solicitar que mi madre viniera al pa\u00eds. Finalmente cumpl\u00ed 21 a\u00f1os y presentamos los papeles. Fue como un sue\u00f1o hecho realidad. Llev\u00f3 mucho tiempo, casi me rindo en un momento dado, pero me siento muy feliz. Siento que mi familia est\u00e1 de nuevo junta.    <\/p>\n<p>Pedro Rios<br \/>\nEntonces, \u00bfc\u00f3mo ser\u00eda una comunidad que ha sido sanada? Creo que esa es una gran pregunta a la que nos enfrentamos nosotros mismos, porque estamos en un proceso de curaci\u00f3n constante. Creo que uno de los procesos de di\u00e1logo ser\u00eda entrar en una conversaci\u00f3n sobre c\u00f3mo caminamos juntos, hombro con hombro, y ese es un aspecto que el Comit\u00e9 del Servicio de los Amigos Americanos ha hecho. Proporcionan los recursos donde podemos caminar juntos con las comunidades.   <\/p>\n<p>&lt;p class=&#8221;chapter&#8221;Qu\u00e9 pueden hacer Los Amigos<\/p>\n<p>Lori Fernald Khamala<br \/>\nCreo que como Amigos tenemos mucho m\u00e1s que ofrecer a esta conversaci\u00f3n, sobre c\u00f3mo reconocemos la luz de Dios en cada individuo, c\u00f3mo tratamos a las personas en general, c\u00f3mo aceptamos un mandato b\u00edblico de acoger al extranjero.<\/p>\n<p>Pedro Rios<br \/>\nSi eres un Amigo que quiere involucrarse y quiere participar en el tema de la inmigraci\u00f3n, yo dir\u00eda, comienza con tu Junta local o comienza con las organizaciones locales con las que ya est\u00e1s en contacto. Ser\u00eda un proceso de, esencialmente, construir desde donde conoces y encontrar formas de conectar y estar en solidaridad con las comunidades en otros lugares. <\/p>\n<p>Lori Fernald Khamala<br \/>\nAs\u00ed que animar\u00eda a todo el mundo a invitar a oradores a sus Juntas, a sus congregaciones, a sus oficinas, a sus grupos escolares, porque hay gente ah\u00ed fuera que est\u00e1 dispuesta a compartir sus historias.<br \/>\nAnimo de verdad a Los Amigos, a otras personas de fe, a que se involucren con el movimiento local por los derechos de los inmigrantes o con el centro local que est\u00e1 trabajando en temas de inmigraci\u00f3n, porque creo que podemos empezar siendo buenos compa\u00f1eros.<\/p>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":4724,"comment_status":"open","ping_status":"closed","template":"","categories":[267,265],"tags":[320,323,324],"class_list":["post-8603","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-activismo-cuaquero","category-video-de-socio","tag-activismo-cuaquero","tag-temporada-2","tag-videos-realizados-en-colaboracion-con-afsc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Amigos y la justicia para los migrantes - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Amigos y la justicia para los migrantes - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:43:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2015\/10\/quakers-and-migrant-justice-PLAY.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/\",\"name\":\"Los Amigos y la justicia para los migrantes - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/10\\\/quakers-and-migrant-justice-PLAY.png\",\"datePublished\":\"2015-10-29T18:22:44+00:00\",\"dateModified\":\"2025-11-06T16:43:42+00:00\",\"description\":\"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/10\\\/quakers-and-migrant-justice-PLAY.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/10\\\/quakers-and-migrant-justice-PLAY.png\",\"width\":1280,\"height\":720,\"caption\":\"Haz clic para ver: \u201cLos Amigos y la justicia para los migrantes\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/los-amigos-y-la-justicia-para-los-migrantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los Amigos y la justicia para los migrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Amigos y la justicia para los migrantes - QuakerSpeak","description":"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/","og_locale":"es_ES","og_type":"article","og_title":"Los Amigos y la justicia para los migrantes - QuakerSpeak","og_description":"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.","og_url":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:43:42+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2015\/10\/quakers-and-migrant-justice-PLAY.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/","url":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/","name":"Los Amigos y la justicia para los migrantes - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2015\/10\/quakers-and-migrant-justice-PLAY.png","datePublished":"2015-10-29T18:22:44+00:00","dateModified":"2025-11-06T16:43:42+00:00","description":"QuakerSpeak explora las perspectivas de Los Amigos sobre la inmigraci\u00f3n, replanteando la noci\u00f3n com\u00fan de que \u201ctenemos un problema de inmigraci\u00f3n\u201d.","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2015\/10\/quakers-and-migrant-justice-PLAY.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2015\/10\/quakers-and-migrant-justice-PLAY.png","width":1280,"height":720,"caption":"Haz clic para ver: \u201cLos Amigos y la justicia para los migrantes\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/los-amigos-y-la-justicia-para-los-migrantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"Los Amigos y la justicia para los migrantes"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/4724"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}