{"id":8589,"date":"2018-06-07T11:44:28","date_gmt":"2018-06-07T15:44:28","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/"},"modified":"2025-11-06T11:43:29","modified_gmt":"2025-11-06T16:43:29","slug":"enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/","title":{"rendered":"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.\n<\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<p style=\"font-size:21px\"><strong>Enriquecimiento para parejas de Amigos: Profundizar la intimidad, encontrar la paz, construir comunidad. \u00bfTienes curiosidad? Vis\u00edtanos en <a href=\"https:\/\/fdsj.nl\/2LmolMm\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/friendscoupleenrichment.org<\/a>  <\/strong> <\/p>\n<div id=\"Transcripci\u00f3n-link-8589\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8589, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8589\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8589\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" title=\"Suscr\u00edbete\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a>Consulta una lista<\/a> de todos los v\u00eddeos que hemos producido.<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<li><a href=\"https:\/\/fdsj.nl\/pym\" target=\"_blank\" rel=\"noopener noreferrer\">M\u00e1s informaci\u00f3n<\/a> sobre los cu\u00e1queros en PA, NJ, DE y MD en <a href=\"\/\/pym.org%E2%80%9D\" target=\"\u201d_blank\u201d\" rel=\"noopener noreferrer\">PYM.org<\/a>.<\/li>\n<li>FCE: profundizando la intimidad, encontrando la paz, construyendo comunidad. \u00bfTienes curiosidad?  <a href=\"https:\/\/fdsj.nl\/fce\" target=\"_blank\" rel=\"noopener noreferrer\">Aprenda m\u00e1s.<\/a><\/li>\n<li><a href=\"https:\/\/fdsj.nl\/friends-fiduciary\" rel=\"noopener noreferrer\" target=\"_blank\">Aprende c\u00f3mo<\/a> Friends Fiduciary da testimonio de los valores cu\u00e1queros en Wall Street<\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Merry Stanford: No hay disciplina espiritual con la que me haya comprometido que haya sido m\u00e1s gratificante, que haya sido m\u00e1s transformadora, que el di\u00e1logo en pareja contigo.<\/p>\n<p class=\"chapter\">Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa<\/p>\n<p>Scott Bell: La Junta de Amigos de Chena Ridge estaba buscando formas tangibles de apoyar el matrimonio que estaba bajo el cuidado de la junta, y una forma fue traer a una pareja l\u00edder de talleres de enriquecimiento para parejas cada dos a\u00f1os, y ese tiempo para nosotros, para tomarnos un tiempo de nuestras ocupadas vidas y poder centrarnos el uno en el otro y en esta relaci\u00f3n, que era tan importante, fue un gran regalo.<\/p>\n<p>Debbie Humphries: Una de las cosas que es tan poderosa sobre el Enriquecimiento para Parejas de Amigos es que est\u00e1 construyendo un conjunto de herramientas para el tipo de relaciones que la gente anhela pero no tiene las herramientas para construir.<\/p>\n<p class=\"chapter\">\u201cRodilla con rodilla\u201d<br \/>\nLa pr\u00e1ctica del di\u00e1logo en pareja<\/p>\n<p><em>Cathy Walling: Es tan amoroso c\u00f3mo trabajamos juntos en el enriquecimiento para parejas, y que hay una parte de nuestros dones juntos que llega a estar en ese pr\u00f3ximo cap\u00edtulo.<\/p>\n<p>Scott Bell: (reflexionando) Entonces, como Cathy, simplemente siento que\u2026<\/em><\/p>\n<p>Merry Stanford: El di\u00e1logo en pareja implica que una pareja se enfrente. Lo llamamos \u201crodilla con rodilla\u201d. As\u00ed que una persona hablar\u00e1 de esa manera, aut\u00e9nticamente, y la otra escuchar\u00e1 y reflejar\u00e1 de alguna manera lo que ha escuchado. E intercambiaremos ese papel.   <\/p>\n<p>Dave Minden: Creo que sabemos esto como cu\u00e1queros. No podemos ser cu\u00e1queros sin una comunidad. En el di\u00e1logo, estamos buscando y ofreciendo nuestra parte de verdad y escuchando la parte de verdad de nuestra pareja.  <\/p>\n<p>Merry Stanford: As\u00ed que cuando Peter se toma el tiempo, acepta sentarse conmigo y escucha intencionalmente y profundamente lo que estoy tratando de traer a mi propia conciencia, me siento vista. Me siento escuchada. Siento que importo. No solo para ti, sino que simplemente importo.   <\/p>\n<p class=\"chapter\">Dialogando en comunidad<\/p>\n<p>Cathy Walling: Estamos invitando a parejas a esta experiencia en una comunidad de parejas, y una parte de lo que se crea a trav\u00e9s de nuestros fines de semana es esta especie de comunidad bendecida de parejas. Es tan contracultural ser invitado a hacer algo como esto con la presencia de testigos. <\/p>\n<p>John Humphries: Parte del valor de hacer esto en comunidad es que puedes ver, \u201c\u00a1Oh! Otras personas tambi\u00e9n tienen estas luchas\u201d. Y podemos proporcionar algo de apoyo, y podemos acercarnos y obtener algo de apoyo. <\/p>\n<p>Cathy Walling: Ayuda a llamar a los individuos a sus lugares de \u201cmejor yo\u201d. Y muy a menudo, tras la reflexi\u00f3n, las parejas dicen: \u201cVaya, no hicimos nuestra t\u00edpica espiral negativa descendente\u201d. <\/p>\n<p>Dave Minden: Fue un momento decisivo, cuando pude decir, \u201caqu\u00ed estamos en conflicto y no tengo que decir esa cosa mala de vuelta. No tengo que ser reactivo. No tengo que justificarme. Simplemente puedo escucharte e intentar reflejar contigo lo que est\u00e1s diciendo\u201d. Cambia la forma en que respondemos el uno al otro. <\/p>\n<p>Pamela Minden: Creo que es un modelo que se necesita desesperadamente ahora mismo, porque hay tantos modelos que convencen a la gente de que la violencia funciona, cuando de hecho no es as\u00ed.<\/p>\n<p class=\"chapter\">Viviendo nuestra Fe cu\u00e1quera<\/p>\n<p>Dave Minden: Los cu\u00e1queros creen que hay algo de lo Divino en cada persona, as\u00ed que de eso se trata realmente el enriquecimiento para parejas. \u00bfC\u00f3mo escucho y presto atenci\u00f3n a lo divino en ti, incluso cuando es en un momento dif\u00edcil? Usando m\u00e9todos de enriquecimiento para parejas como una forma de decir, \u201cQuiero estar en paz contigo, incluso en este momento\u201d.  <\/p>\n<p>Cathy Walling: \u00bfCon qu\u00e9 frecuencia vemos a parejas en p\u00fablico discutiendo? En contraste, \u00bfcon qu\u00e9 frecuencia podemos presenciar a parejas expresando aut\u00e9nticamente su amor y cuidado mutuo? C\u00f3mo eso puede transformar nuestro mundo, si esa fuera la forma.  <\/p>\n<p><em>Peter Wood: As\u00ed que no estoy seguro de lo que podr\u00edamos decir en la segunda parte de nuestro di\u00e1logo, pero me siento listo para hacer una pausa aqu\u00ed.<\/p>\n<p>Merry Stanford: Nunca sabemos lo que vamos a decir en el pr\u00f3ximo di\u00e1logo.<\/p>\n<p>Peter Wood: \u00a1Pero hasta ahora, todo bien!<\/em><\/p>\n<h3>Preguntas para el debate:<\/h3>\n<ul>\n<li>\u00bfC\u00f3mo se manifiesta el compromiso cu\u00e1quero con la paz de maneras que no son obvias? \u00bfC\u00f3mo se manifiesta en nuestras relaciones personales? <\/li>\n<li>\u00bfQu\u00e9 herramientas has aprendido para estar en paz con tu pareja? \u00bfC\u00f3mo se ve afectado tu enfoque de esas relaciones por tu cuaquerismo?\n<\/li>\n<\/ul>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":6263,"comment_status":"open","ping_status":"closed","template":"","categories":[265],"tags":[340],"class_list":["post-8589","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-video-de-socio","tag-temporada-5"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:43:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/06\/friends-couple-enrichment-FB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/\",\"name\":\"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/friends-couple-enrichment-FB.png\",\"datePublished\":\"2018-06-07T15:44:28+00:00\",\"dateModified\":\"2025-11-06T16:43:29+00:00\",\"description\":\"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/friends-couple-enrichment-FB.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/friends-couple-enrichment-FB.png\",\"width\":1200,\"height\":637},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak","description":"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak","og_description":"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.","og_url":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:43:29+00:00","og_image":[{"width":1200,"height":637,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/06\/friends-couple-enrichment-FB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/","url":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/","name":"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/06\/friends-couple-enrichment-FB.png","datePublished":"2018-06-07T15:44:28+00:00","dateModified":"2025-11-06T16:43:29+00:00","description":"Los cu\u00e1queros creen que hay \u201calgo de Dios en cada persona\u201d. Aqu\u00ed te mostramos c\u00f3mo puede manifestarse en nuestras relaciones rom\u00e1nticas.","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/06\/friends-couple-enrichment-FB.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/06\/friends-couple-enrichment-FB.png","width":1200,"height":637},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/enriquecimiento-para-parejas-de-amigos-la-pacificacion-empieza-en-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"Enriquecimiento para parejas de Amigos: la pacificaci\u00f3n empieza en casa"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/6263"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}