{"id":8571,"date":"2018-10-24T15:54:37","date_gmt":"2018-10-24T19:54:37","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/ser-las-manos-de-dios\/"},"modified":"2025-11-06T11:43:18","modified_gmt":"2025-11-06T16:43:18","slug":"ser-las-manos-de-dios","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/","title":{"rendered":"Ser las manos de Dios"},"content":{"rendered":"<div class=\"video-container\"><div class=\"youtube-embed\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/=\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><\/div>\n<p style=\"margin-top: 25px\">Cuando Carter Nash decidi\u00f3 tomarse en serio el vers\u00edculo b\u00edblico \u201cDios es amor\u201d, todo cambi\u00f3.\n<\/p>\n<div style=\"width: 320px;margin: 0 auto\"><\/div>\n<div style=\"width:200px;margin:20px auto;margin-bottom:0px\"><em>\u00bfMerece la pena QuakerSpeak 1 $ por v\u00eddeo?<\/em><br \/>\n<a href=\"https:\/\/fdsj.nl\/patreon2\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/2017\/05\/patreon_logo-small.png\"><\/a><\/div>\n<div id=\"Transcripci\u00f3n-link-8571\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8571, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8571\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8571\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" title=\"Suscr\u00edbete\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a>Consulta una lista<\/a> de todos los v\u00eddeos que hemos producido.<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<li><a href=\"https:\/\/fdsj.nl\/pym\" target=\"_blank\" rel=\"noopener noreferrer\">M\u00e1s informaci\u00f3n<\/a> sobre los cu\u00e1queros en PA, NJ, DE y MD en <a href=\"\/\/pym.org%E2%80%9D\" target=\"\u201d_blank\u201d\" rel=\"noopener noreferrer\">PYM.org<\/a>.<\/li>\n<li>FCE: profundizando la intimidad, encontrando la paz, construyendo comunidad. \u00bfTienes curiosidad?  <a href=\"https:\/\/fdsj.nl\/fce\" target=\"_blank\" rel=\"noopener noreferrer\">Aprenda m\u00e1s.<\/a><\/li>\n<li><a href=\"https:\/\/fdsj.nl\/friends-fiduciary\" rel=\"noopener noreferrer\" target=\"_blank\">Aprende c\u00f3mo<\/a> Friends Fiduciary da testimonio de los valores cu\u00e1queros en Wall Street<\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Creo que caminar por un sendero de amor es justo lo que se necesita. Creo que es algo que se inculc\u00f3 mucho antes de que me hiciera cu\u00e1quero. Cuando encontr\u00e9 la Junta de Los Amigos, fue como, \u201cGuau, esta gente realmente cree en esto y lo practica\u201d.  <\/p>\n<p class=\"chapter\">Ser las manos de Dios<\/p>\n<p>Soy Carter Nash, vivo en Lower Paxton, Pensilvania, que est\u00e1 justo a las afueras de Harrisburg, Pensilvania, y mi Junta es la Junta Mensual de Harrisburg de la Sociedad Religiosa de los Amigos.<\/p>\n<p>Los cu\u00e1queros creen en esa parte de Dios en cada persona. Recientemente, he redefinido bastante para m\u00ed mismo c\u00f3mo pienso en el t\u00e9rmino Dios. Se remonta a un pasaje b\u00edblico. Ese pasaje es, \u201cDios es amor\u201d y, por lo tanto, pienso en \u201cesa parte de Dios en cada persona\u201d como esa parte de amor en cada persona, y as\u00ed trato de relacionarme con todos con amor. Entre los cu\u00e1queros, he descubierto que eso es lo que hacen conmigo.    <\/p>\n<p class=\"chapter\">Responder con amor<\/p>\n<p>Pensar en Dios como amor es una cuesti\u00f3n de que el amor dirija todo en la vida. Si alguien hace algo que podr\u00eda enfadarme, responder con amor. Si hay odio a mi alrededor, buscar c\u00f3mo puedo abordarlo de una manera amorosa porque eso es lo que creo que Dios dentro de m\u00ed y Dios dentro de las otras personas quieren.   <\/p>\n<p>Creo que la gente responder\u00e1 al amor, porque creo que la gente responde a Dios. Y si Dios es amor, a lo que la gente responder\u00e1 es al amor. Creo que esa es la clave de muchas cosas y de muchos problemas en el mundo, porque si realmente creemos en Dios y realmente creemos que Dios es amor como se nos ense\u00f1\u00f3, y actuamos en consecuencia, y creo que somos las manos de Dios aqu\u00ed, entonces todo lo que hacemos debe estar arraigado en el amor.  <\/p>\n<p class=\"chapter\">Recargar energ\u00edas<\/p>\n<p>La Junta de adoraci\u00f3n ayuda a recargarme y revitalizarme. Cuando nos reunimos en silencio, nos estamos abriendo. Hacemos lo que llamamos \u201ccentrarnos\u201d, y eso es abrirnos para permitir que el esp\u00edritu de Dios nos invada por completo. Despu\u00e9s de que termina la Junta, salimos al mundo y hacemos el servicio de Dios, y hacemos su trabajo.   <\/p>\n<p>As\u00ed es como la Junta de adoraci\u00f3n ayuda a conectarme a tierra y as\u00ed es como mi cuaquerismo ayuda a conectarme a tierra. S\u00e9 que en cualquier momento, puedo sentarme solo en cualquier lugar y aprovechar esa energ\u00eda. Ese amor que est\u00e1 en m\u00ed, simplemente contin\u00faa. El amor que me muestran Los Amigos y que veo que nos mostramos a los dem\u00e1s me da energ\u00eda para transmitirlo y seguir haci\u00e9ndolo.  <\/p>\n<h3>Preguntas para el debate:<\/h3>\n<ul>\n<li>\u00bfAlguna vez has pensado seriamente en el pasaje \u201cDios es amor\u201d? Si eso es cierto, \u00bfqu\u00e9 significa para ti? <\/li>\n<li>Carter Nash dice: \u201cPienso en \u2018esa parte de Dios en cada persona\u2019 como esa parte de amor en cada persona, y as\u00ed trato de relacionarme con todos con amor\u201d. Si los cu\u00e1queros honran esa parte de Dios en cada persona y Dios es amor, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo nos relacionamos con quienes nos rodean?\n<\/li>\n<\/ul>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":6371,"comment_status":"open","ping_status":"closed","template":"","categories":[263,273],"tags":[340,321],"class_list":["post-8571","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-entrevista","category-teologia-cuaquera","tag-temporada-5","tag-teologia-y-creencias-de-los-amigos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ser las manos de Dios - QuakerSpeak<\/title>\n<meta name=\"description\" content=\"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ser las manos de Dios - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:43:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/10\/being-gods-hands-FB2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/\",\"name\":\"Ser las manos de Dios - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/being-gods-hands-FB2.png\",\"datePublished\":\"2018-10-24T19:54:37+00:00\",\"dateModified\":\"2025-11-06T16:43:18+00:00\",\"description\":\"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/being-gods-hands-FB2.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/being-gods-hands-FB2.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/ser-las-manos-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ser las manos de Dios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ser las manos de Dios - QuakerSpeak","description":"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/","og_locale":"es_ES","og_type":"article","og_title":"Ser las manos de Dios - QuakerSpeak","og_description":"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?","og_url":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:43:18+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/10\/being-gods-hands-FB2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/","url":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/","name":"Ser las manos de Dios - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/10\/being-gods-hands-FB2.png","datePublished":"2018-10-24T19:54:37+00:00","dateModified":"2025-11-06T16:43:18+00:00","description":"Si Dios es amor y somos las manos de Dios, \u00bfqu\u00e9 significa eso en cuanto a c\u00f3mo deber\u00edamos mostrarnos en el mundo?","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/10\/being-gods-hands-FB2.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2018\/10\/being-gods-hands-FB2.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/ser-las-manos-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"Ser las manos de Dios"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/6371"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}