{"id":8508,"date":"2023-08-17T16:00:02","date_gmt":"2023-08-17T20:00:02","guid":{"rendered":"https:\/\/quakerspeak.com\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/"},"modified":"2025-11-06T11:41:23","modified_gmt":"2025-11-06T16:41:23","slug":"hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo","status":"publish","type":"fpb_video","link":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/","title":{"rendered":"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Growing the Community of Friends - Embracing Diversity in Quakerism\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mAb9b_vbgXQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p>\u00abGeorge Fox, Los 60 Valientes&#8230; Sea quien sea tu h\u00e9roe cu\u00e1quero favorito, [ellos] no hicieron este trabajo para que muriera por lazos de sangre\u00bb, nos dijo recientemente Rashid Darden. \u00abSe supone que debe continuar. Se supone que la revelaci\u00f3n debe continuar a trav\u00e9s de los cuerpos, a trav\u00e9s de personas vivas que luego puedan cont\u00e1rselo a otros\u00bb <\/p>\n\n<p>\u00abLo sorprendente de mi viaje en la fe cu\u00e1quera\u00bb, a\u00f1ade Rashid, \u00abes que, a pesar de ser una comunidad de fe predominantemente blanca, sigo siendo capaz de mostrarme como mi ser completo y no ser penalizado ni castigado por ello, sino, de hecho, ser celebrado\u00bb.<\/p>\n\n<p>Como secretario asociado de comunicaciones y divulgaci\u00f3n en la Conferencia General de Los Amigos (FGC), Rashid tiene mucho que decir sobre c\u00f3mo Los Amigos pueden ofrecer espacios igualmente liberadores en sus comunidades.<\/p>\n\n<p><em>Algunas partes de esta entrevista tambi\u00e9n aparecieron en <\/em><a href=\"https:\/\/www.friendsjournal.org\/podcast\/quakers-fiction-and-virginia-woolf\/\"><em>un episodio del <\/em>Quakers Today <em>p\u00f3dcast<\/em><\/a><em>.<\/em><\/p>\n<div id=\"Transcripci\u00f3n-link-8508\" class=\"sh-link Transcripci\u00f3n-link sh-hide\"><a href=\"#\" onclick=\"showhide_toggle('Transcripci\u00f3n', 8508, 'Mostrar transcripci\u00f3n y preguntas para el debate', 'Ocultar transcripci\u00f3n y preguntas para el debate'); return false;\" aria-expanded=\"false\"><span id=\"Transcripci\u00f3n-toggle-8508\">Mostrar transcripci\u00f3n y preguntas para el debate<\/span><\/a><\/div><div id=\"Transcripci\u00f3n-content-8508\" class=\"sh-content Transcripci\u00f3n-content sh-hide\" style=\"display: none;\"><\/p>\n<h3>Recursos:<\/h3>\n<ul>\n<li><a title=\"Suscr\u00edbete\" href=\"https:\/\/quakerspeak.com\/es\/suscribete\/\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbete<\/a> a QuakerSpeak para no perderte nunca un v\u00eddeo<\/li>\n<li><a title=\"\u201cQuakerSpeak\" href=\"https:\/\/fdsj.nl\/all-videos\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta una lista<\/a> de todos los v\u00eddeos que hemos producido.<\/li>\n<li><a href=\"https:\/\/www.friendsjournal.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lee Friends Journal<\/a> para ver c\u00f3mo otros Amigos describen la esencia de la espiritualidad cu\u00e1quera<\/li>\n<\/ul>\n<h3>Transcripci\u00f3n:<\/h3>\n<p>Lo sorprendente de mi viaje en la fe cu\u00e1quera es que, a pesar de ser una comunidad de fe predominantemente blanca, sigo siendo capaz de mostrarme como mi ser completo y no ser penalizado ni castigado por ello y, de hecho, ser celebrado por ello. Y me doy cuenta de que, en la fe cu\u00e1quera y en las personas que se identifican como Los Amigos, todos somos impenitentes a nuestra manera sobre nuestras formas de ser y de mostrarnos en el mundo. Y no puedo evitar pensar que eso es una intervenci\u00f3n divina. Eso no es m\u00e1s que Dios, eso no es \u00abtodos le\u00edmos el mismo libro y llegamos a las mismas conclusiones&#8221;. Es que miramos dentro de nosotros mismos, y escuchamos, y fuimos conducidos al mismo lugar.    <\/p>\n<p>Me llamo Rashid Darden. Mis pronombres son \u00e9l\/\u00e9l\/suyo, vivo en Conway, Carolina del Norte. Y adoro con la Junta de Los Amigos de Washington en Washington, D.C., virtualmente a las nueve en punto.  <\/p>\n<p>Es dif\u00edcil articular lo que eres a personas que simplemente puede que no est\u00e9n ah\u00ed, puede que no est\u00e9n interesadas, o hay otras comunidades de fe que son m\u00e1s predominantes. La Sociedad Religiosa de los Amigos es una de las denominaciones m\u00e1s peque\u00f1as, si se quiere, al menos en Norteam\u00e9rica. La fe cu\u00e1quera es en gran medida blanca en este pa\u00eds y es muy, en algunos lugares, de clase media y en algunos lugares muy agraria. As\u00ed que, si queremos diversificar la Sociedad Religiosa de los Amigos en lugares como Nueva York o Washington, est\u00e1s, ya sabes, si est\u00e1s buscando gente negra, est\u00e1s compitiendo con la tradici\u00f3n protestante negra.   <\/p>\n<p>Pero no creo que la respuesta sea simplemente \u00abVamos a buscar una comunidad. Vamos a buscar un segmento en particular&#8221;. Hay datos por ah\u00ed que hablan de personas que est\u00e1n tomando la decisi\u00f3n de ser espirituales pero no religiosas. Lo que mucha gente est\u00e1 haciendo es dejar el cristianismo por completo. Y yo dir\u00eda, como alguien que casi no fue cristiano, que la fe cu\u00e1quera fue la \u00faltima parada antes de que decidiera no ser religioso en absoluto. Creo que esa deber\u00eda ser la narrativa predominante y que no podemos propagar la fe cu\u00e1quera teniendo beb\u00e9s y esperando que decidan ser cu\u00e1queros. Deber\u00edamos propagarnos hacia fuera tanto como nos propagamos hacia arriba y hacia abajo, si eso tiene sentido.     <\/p>\n<p>Adem\u00e1s de entender que deber\u00edamos estar atrapando a la gente antes de que se vaya de dondequiera que fuera su primer hogar, tenemos que hacer cosas inteligentes como literatura biling\u00fce. Que si est\u00e1s en una ciudad como Washington con muchos inmigrantes de habla hispana, los materiales de tu Junta deben estar en espa\u00f1ol o am\u00e1rico o franc\u00e9s o lo que funcione para tu comunidad local. Tenemos que experimentar con los d\u00edas y horarios de las Juntas. Tenemos que experimentar con la adoraci\u00f3n como una pr\u00e1ctica comunitaria, es decir, parte de una Junta mensual, o la adoraci\u00f3n como un servicio. Entidades como la Conferencia General de Los Amigos y Pendle Hill ofrecen adoraci\u00f3n virtual, lo cual es muy importante, y espero que esas experiencias tambi\u00e9n compartan el siguiente paso l\u00f3gico: Aqu\u00ed est\u00e1 c\u00f3mo encontrar una comunidad propia. Aqu\u00ed est\u00e1 c\u00f3mo pasar de ser receptores de un servicio a participantes en una comunidad. Y si nuestras entidades, cualesquiera que sean nuestras entidades cu\u00e1queras, no est\u00e1n haciendo eso, entonces no est\u00e1n invirtiendo en el crecimiento de la Sociedad Religiosa de los Amigos.      <\/p>\n<p>Deber\u00edamos invertir recursos en personas que dominen los idiomas de las comunidades que queremos atraer. Y eso no significa solo idiomas extranjeros. Eso significa alguien como yo, que viene de una experiencia protestante particular, de un tipo particular de ciudad que est\u00e1 impregnada de una tradici\u00f3n pro-negra. \u00bfC\u00f3mo generamos las conversaciones en torno a c\u00f3mo atraer a gente que se parece a m\u00ed? Si la gente que se parece a m\u00ed no est\u00e1 en el liderazgo de esas iniciativas. Esas son cosas en las que pensar. Esas son cosas de las que hablar. Pero, lo que es m\u00e1s importante, esas son cosas en las que actuar. Incluso si fracasamos, tenemos que estar de acuerdo con fracasar y pivotar y causar la menor cantidad de da\u00f1o. Pero causamos m\u00e1s da\u00f1o a la comunidad cuando no lo intentamos.         <\/p>\n<p>Creo que tenemos que deshacernos del miedo. Y creo que tenemos que ponernos la armadura que necesitemos para hacer este trabajo. La fe cu\u00e1quera no es un club de campo. No es una sociedad de legado. El cu\u00e1quero m\u00e1s importante es el amigo que a\u00fan no est\u00e1 convencido. Mi ministerio personal es uno que est\u00e1 tan convencido de que el cuaquerismo es uno de los mejores caminos posibles a seguir que estar\u00eda mal que me callara al respecto, que estar\u00eda mal que no compartiera mi historia, George Fox, Los 60 Valientes, sea quien sea tu h\u00e9roe cu\u00e1quero favorito, no hizo este trabajo para que pudiera morir por lazos de sangre. Se supone que debe continuar. Se supone que la revelaci\u00f3n debe continuar a trav\u00e9s de los cuerpos, a trav\u00e9s de personas vivas que luego puedan cont\u00e1rselo a otros.       <\/p>\n<h3>Pregunta para el debate:<\/h3>\n<ul>\n<li>\u00bfC\u00f3mo hacemos crecer y diversificamos la Comunidad Cu\u00e1quera? <\/li>\n<\/ul>\n<p><em>Las opiniones expresadas en este v\u00eddeo son de los oradores y no reflejan necesariamente las opiniones de Friends Journal ni de sus colaboradores.<\/em><br \/>\n<\/div>\n","protected":false},"featured_media":7141,"comment_status":"open","ping_status":"closed","template":"","categories":[275,263,269,264],"tags":[],"class_list":["post-8508","fpb_video","type-fpb_video","status-publish","has-post-thumbnail","hentry","category-cuaqueros-de-color-hablan","category-entrevista","category-fe-y-practica-cuaquera","category-lgbtq"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak\" \/>\n<meta property=\"og:description\" content=\"\u00abGeorge Fox, Los 60 Valientes&#8230; Sea quien sea tu h\u00e9roe cu\u00e1quero favorito, [ellos] no hicieron este trabajo para que muriera&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/\" \/>\n<meta property=\"og:site_name\" content=\"QuakerSpeak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:41:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2023\/08\/Thumbnail_2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/\",\"name\":\"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/08\\\/Thumbnail_2.png\",\"datePublished\":\"2023-08-17T20:00:02+00:00\",\"dateModified\":\"2025-11-06T16:41:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/08\\\/Thumbnail_2.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/08\\\/Thumbnail_2.png\",\"width\":1280,\"height\":720,\"caption\":\"QuakerSpeak: haciendo crecer la comunidad de Los Amigos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeos\",\"item\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"name\":\"QuakerSpeak\",\"description\":\"Weekly Videos. Vital Ministries.\",\"publisher\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#organization\",\"name\":\"QuakerSpeak\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"contentUrl\":\"https:\\\/\\\/quakerspeak.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/Without-BG-3.png\",\"width\":181,\"height\":66,\"caption\":\"QuakerSpeak\"},\"image\":{\"@id\":\"https:\\\/\\\/quakerspeak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/","og_locale":"es_ES","og_type":"article","og_title":"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak","og_description":"\u00abGeorge Fox, Los 60 Valientes&#8230; Sea quien sea tu h\u00e9roe cu\u00e1quero favorito, [ellos] no hicieron este trabajo para que muriera&hellip;","og_url":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/","og_site_name":"QuakerSpeak","article_modified_time":"2025-11-06T16:41:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2023\/08\/Thumbnail_2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/","url":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/","name":"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo - QuakerSpeak","isPartOf":{"@id":"https:\/\/quakerspeak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/#primaryimage"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/#primaryimage"},"thumbnailUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2023\/08\/Thumbnail_2.png","datePublished":"2023-08-17T20:00:02+00:00","dateModified":"2025-11-06T16:41:23+00:00","breadcrumb":{"@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/#primaryimage","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2023\/08\/Thumbnail_2.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2023\/08\/Thumbnail_2.png","width":1280,"height":720,"caption":"QuakerSpeak: haciendo crecer la comunidad de Los Amigos"},{"@type":"BreadcrumbList","@id":"https:\/\/quakerspeak.com\/es\/video\/hacer-crecer-la-comunidad-de-los-amigos-abrazar-la-diversidad-en-el-cuaquerismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quakerspeak.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeos","item":"https:\/\/quakerspeak.com\/es\/video\/"},{"@type":"ListItem","position":3,"name":"Hacer crecer la comunidad de Los Amigos: abrazar la diversidad en el cuaquerismo"}]},{"@type":"WebSite","@id":"https:\/\/quakerspeak.com\/es\/#website","url":"https:\/\/quakerspeak.com\/es\/","name":"QuakerSpeak","description":"Weekly Videos. Vital Ministries.","publisher":{"@id":"https:\/\/quakerspeak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quakerspeak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quakerspeak.com\/es\/#organization","name":"QuakerSpeak","url":"https:\/\/quakerspeak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","contentUrl":"https:\/\/quakerspeak.com\/wp-content\/uploads\/sites\/2\/2024\/03\/Without-BG-3.png","width":181,"height":66,"caption":"QuakerSpeak"},"image":{"@id":"https:\/\/quakerspeak.com\/es\/#\/schema\/logo\/image\/"}}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"QuakerSpeak","distributor_original_site_url":"https:\/\/quakerspeak.com\/es\/","push-errors":false,"acf":[],"_links":{"self":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video\/8508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/fpb_video"}],"about":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/types\/fpb_video"}],"replies":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/comments?post=8508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media\/7141"}],"wp:attachment":[{"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/media?parent=8508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/categories?post=8508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quakerspeak.com\/es\/wp-json\/wp\/v2\/tags?post=8508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}